{"id":1645,"date":"2026-03-03T13:13:57","date_gmt":"2026-03-03T16:13:57","guid":{"rendered":"https:\/\/boracultura.com.br\/?p=1645"},"modified":"2026-03-04T23:46:11","modified_gmt":"2026-03-05T02:46:11","slug":"teatro-gamboa-divulga-programacao-de-marco-com-teatro-musica-e-exposicao-em-salvador","status":"publish","type":"post","link":"https:\/\/boracultura.com.br\/index.php\/2026\/03\/03\/teatro-gamboa-divulga-programacao-de-marco-com-teatro-musica-e-exposicao-em-salvador\/","title":{"rendered":"Teatro Gamboa divulga programa\u00e7\u00e3o de mar\u00e7o com teatro, m\u00fasica e exposi\u00e7\u00e3o em Salvador"},"content":{"rendered":"\n<p>Abrindo a programa\u00e7\u00e3o da primeira semana de mar\u00e7o, o Teatro Gamboa recebe nesta quarta (04), \u00e0s 19h, a segunda apresenta\u00e7\u00e3o da temporada do espet\u00e1culo &#8220;O Av\u00f4 e o Rio&#8221;, primeiro solo do ator Israel Barreto, integrante do coletivo Duo. A montagem nasce do conto hom\u00f4nimo do escritor baiano Aleilton Fonseca, membro da Academia de Letras da Bahia, e transforma em poesia c\u00eanica a rela\u00e7\u00e3o entre um neto, seu av\u00f4 e o rio que atravessa suas exist\u00eancias. O espet\u00e1culo, que seguir\u00e1 por todas as quartas-feiras de mar\u00e7o, prop\u00f5e um mergulho sens\u00edvel no tempo, na natureza e nas rela\u00e7\u00f5es humanas em um convite para revisitar as \u00e1guas que nos formam e refletir sobre os espa\u00e7os que a moderniza\u00e7\u00e3o insiste em aterrar. Os ingressos custam&nbsp;<a href=\"https:\/\/bileto.sympla.com.br\/event\/116451\" target=\"_blank\" rel=\"noreferrer noopener\">R$25\/R$50<\/a>, para assistir presencialmente, e&nbsp;<a href=\"https:\/\/www.sympla.com.br\/evento-online\/o-avo-e-o-rio-online---ao-vivo---0403\/3309786\" target=\"_blank\" rel=\"noreferrer noopener\">R$15<\/a>&nbsp;para assistir na plataforma virtual do teatro.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/03\/Carlos-A.-Lopes-1-credito-Arthur-Lopes-Carlos-A.-Lopes-1024x683.png\" alt=\"\" class=\"wp-image-1648\" srcset=\"https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/03\/Carlos-A.-Lopes-1-credito-Arthur-Lopes-Carlos-A.-Lopes-1024x683.png 1024w, https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/03\/Carlos-A.-Lopes-1-credito-Arthur-Lopes-Carlos-A.-Lopes-300x200.png 300w, https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/03\/Carlos-A.-Lopes-1-credito-Arthur-Lopes-Carlos-A.-Lopes-768x513.png 768w, https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/03\/Carlos-A.-Lopes-1-credito-Arthur-Lopes-Carlos-A.-Lopes.png 1500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Cr\u00e9dito Arthur Lopes<\/figcaption><\/figure>\n\n\n\n<p>No dia seguinte (05), \u00e0s 19h, o compositor Carlos A. Lopes, em um mergulho no seu repert\u00f3rio que \u00e9 uma imers\u00e3o em experi\u00eancias ligadas \u00e0 cidade de Salvador, onde as viv\u00eancias na defesa do meio ambiente serviram como inspira\u00e7\u00e3o. As \u00e1guas dos rios e da Ba\u00eda de Todos os Santos tamb\u00e9m s\u00e3o temas recorrentes do seu trabalho e o repert\u00f3rio do show &#8220;\u00c1guas, montanhas, poesias e rios&#8221; revela isso. Duarte Velloso participa do show na dire\u00e7\u00e3o musical e no viol\u00e3o. A banda conta ainda com o flautista Kiko Souza e o percussionista Marcelo Pinho. Os ingressos custam&nbsp;<a href=\"https:\/\/bileto.sympla.com.br\/event\/116643\/d\/366918\/s\/2465955\" target=\"_blank\" rel=\"noreferrer noopener\">R$25\/R$50<\/a>, para assistir presencialmente, e&nbsp;<a href=\"https:\/\/www.sympla.com.br\/evento-online\/Aguas-montanhas-poesias-e-rios-online---ao-vivo\/3320382\" target=\"_blank\" rel=\"noreferrer noopener\">R$15<\/a>&nbsp;para assistir na plataforma virtual do teatro.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"684\" src=\"https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/03\/QUANDO-O-CORACAO-TRANSBORDA-FOTO-DE-ANDREA-POSSAMAI-Esquadrao-da-Vida-Companhia-de-Teatro-1024x684.jpg\" alt=\"\" class=\"wp-image-1651\" srcset=\"https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/03\/QUANDO-O-CORACAO-TRANSBORDA-FOTO-DE-ANDREA-POSSAMAI-Esquadrao-da-Vida-Companhia-de-Teatro-1024x684.jpg 1024w, https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/03\/QUANDO-O-CORACAO-TRANSBORDA-FOTO-DE-ANDREA-POSSAMAI-Esquadrao-da-Vida-Companhia-de-Teatro-300x200.jpg 300w, https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/03\/QUANDO-O-CORACAO-TRANSBORDA-FOTO-DE-ANDREA-POSSAMAI-Esquadrao-da-Vida-Companhia-de-Teatro-768x513.jpg 768w, https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/03\/QUANDO-O-CORACAO-TRANSBORDA-FOTO-DE-ANDREA-POSSAMAI-Esquadrao-da-Vida-Companhia-de-Teatro-1536x1025.jpg 1536w, https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/03\/QUANDO-O-CORACAO-TRANSBORDA-FOTO-DE-ANDREA-POSSAMAI-Esquadrao-da-Vida-Companhia-de-Teatro-2048x1367.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Foto de \u00c2ndrea Possamai<\/figcaption><\/figure>\n\n\n\n<p>Espet\u00e1culo que une teatro, viola caipira e mem\u00f3ria afetiva, &#8220;Quando o cora\u00e7\u00e3o transborda&#8221; estreia temporada nesta sexta-feira (06), \u00e0s 19h. O mon\u00f3logo de Ma\u00edra Oliveira ser\u00e1 apresentado todas as sextas de mar\u00e7o no Gamboa. Sozinha em cena, Ma\u00edra canta, toca viola caipira e viol\u00e3o e conduz o espectador por mem\u00f3rias, cartas, can\u00e7\u00f5es e reflex\u00f5es sobre arte, heran\u00e7a e resist\u00eancia cultural. A montagem transforma hist\u00f3rias pessoais em experi\u00eancia coletiva, aproximando plateia e artista em um formato pensado para pequenos teatros. O espet\u00e1culo nasceu em 2015 a partir da hist\u00f3ria do Esquadr\u00e3o da Vida, grupo de teatro de rua fundado em Bras\u00edlia, em 1979, por Ary P\u00e1ra-Raios, pai e mestre de Ma\u00edra. Os ingressos custam&nbsp;<a href=\"https:\/\/bileto.sympla.com.br\/event\/116457\" target=\"_blank\" rel=\"noreferrer noopener\">R$20\/R$40<\/a>, para assistir presencialmente, e&nbsp;<a href=\"https:\/\/www.sympla.com.br\/evento-online\/quando-o-coracao-transborda-onloine---ao-vivo---0603\/3309817\" target=\"_blank\" rel=\"noreferrer noopener\">R$15<\/a>&nbsp;para assistir pela plataforma virtual do Gamboa.<\/p><div class=\"borac-publicidade-no-post borac-entity-placement\" style=\"text-align: center;\" id=\"borac-1119676680\"><div id=\"borac-1967632090\"><a href=\"https:\/\/bileto.sympla.com.br\/event\/118627\/d\/375887\/s\/2508765\" aria-label=\"MINHA M\u00c3E E EU_teatro m\u00f3dulo (970x250px)\"><img src=\"https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/05\/MINHA-MAE-E-EU_teatro-modulo-970x250px.png\" alt=\"\"  srcset=\"https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/05\/MINHA-MAE-E-EU_teatro-modulo-970x250px.png 970w, https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/05\/MINHA-MAE-E-EU_teatro-modulo-970x250px-300x77.png 300w, https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/05\/MINHA-MAE-E-EU_teatro-modulo-970x250px-768x198.png 768w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"250\"   \/><\/a><\/div><\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/03\/Teco-Aziz-Show-Armengue-Foto-Gabriel-Kelly-Fabio-Lacerda-1024x683.jpg\" alt=\"\" class=\"wp-image-1650\" srcset=\"https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/03\/Teco-Aziz-Show-Armengue-Foto-Gabriel-Kelly-Fabio-Lacerda-1024x683.jpg 1024w, https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/03\/Teco-Aziz-Show-Armengue-Foto-Gabriel-Kelly-Fabio-Lacerda-300x200.jpg 300w, https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/03\/Teco-Aziz-Show-Armengue-Foto-Gabriel-Kelly-Fabio-Lacerda-768x512.jpg 768w, https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/03\/Teco-Aziz-Show-Armengue-Foto-Gabriel-Kelly-Fabio-Lacerda.jpg 1392w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Foto: Gabriel Kelly<\/figcaption><\/figure>\n\n\n\n<p>O &#8220;Armengue \u2014 Especial de Ver\u00e3o&#8221; chega ao palco do Gamboa no s\u00e1bado (07), \u00e0s 17h. Nele, os comediantes F\u00e1bio Lacerda, T\u00eaco Aziz e Victor Fadigas recebem convidados da cena da com\u00e9dia baiana e v\u00e3o levar as resenhas vividas por eles na esta\u00e7\u00e3o. Eles se revezam no palco com textos autorais sobre suas viv\u00eancias e percep\u00e7\u00f5es do mundo&nbsp;ao seu redor para garantir a divers\u00e3o do p\u00fablico. Os ingressos custam&nbsp;<a href=\"https:\/\/bileto.sympla.com.br\/event\/116461\" target=\"_blank\" rel=\"noreferrer noopener\">R$12,50\/R$25<\/a>&nbsp;para assistir presencialmente, e&nbsp;<a href=\"https:\/\/www.sympla.com.br\/evento-online\/armengue---stand-up-comedy---especial-de-verao-online---ao-vivo\/3309863\" target=\"_blank\" rel=\"noreferrer noopener\">R$15<\/a>&nbsp;para assistir pela plataforma virtual do Gamboa.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/03\/7T4A1888_FOTO_Caio_Lirio_ig_caiolirio-1-1-1-1-1024x683.jpg\" alt=\"\" class=\"wp-image-1652\" srcset=\"https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/03\/7T4A1888_FOTO_Caio_Lirio_ig_caiolirio-1-1-1-1-1024x683.jpg 1024w, https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/03\/7T4A1888_FOTO_Caio_Lirio_ig_caiolirio-1-1-1-1-300x200.jpg 300w, https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/03\/7T4A1888_FOTO_Caio_Lirio_ig_caiolirio-1-1-1-1-768x512.jpg 768w, https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/03\/7T4A1888_FOTO_Caio_Lirio_ig_caiolirio-1-1-1-1-1536x1024.jpg 1536w, https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/03\/7T4A1888_FOTO_Caio_Lirio_ig_caiolirio-1-1-1-1-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Foto: Caio Lirio<\/figcaption><\/figure>\n\n\n\n<p>Depois de esgotar sess\u00f5es na temporada entre janeiro e fevereiro, o espet\u00e1culo &#8220;Crian\u00e7a Viada ou de como me disseram que eu era gay&#8221; volta a cartaz nos domingos do Gamboa, a partir das 17h. Estreando no dia 08, o solo de Vinicius Bustani, tamb\u00e9m autor do texto, com dire\u00e7\u00e3o e dramaturgia de Paula Lice, parte de experi\u00eancias pessoais de Vinic\u00edus para falar de um tema comum que \u00e9 a LGBTfobia vivida por crian\u00e7as e adolescentes. &#8220;A pe\u00e7a \u00e9 a partilha de um processo que se deu h\u00e1 mais de vinte anos e, mesmo com todas as mudan\u00e7as e avan\u00e7os que tivemos nesse \u00e2mbito, encontrou eco e sentido em adolescentes e jovens em 2018. N\u00e3o acho que muita coisa tenha mudado desde ent\u00e3o&#8221;, comenta o ator. Os ingressos custam&nbsp;<a href=\"https:\/\/bileto.sympla.com.br\/event\/114586\/d\/364399\/s\/2453826\" target=\"_blank\" rel=\"noreferrer noopener\">R$25\/R$50<\/a>&nbsp;para assistir presencialmente, e&nbsp;<a href=\"https:\/\/www.sympla.com.br\/evento-online\/crianca-viada-ou-de-como-me-disseram-que-eu-era-gay-online-ao-vivo-08-03\/3309883\" target=\"_blank\" rel=\"noreferrer noopener\">R$15<\/a>&nbsp;para assistir pela plataforma virtual do Gamboa.<\/p>\n\n\n\n<p>Antes de cada apresenta\u00e7\u00e3o acontece o CineGamboa, com a exibi\u00e7\u00e3o do v\u00eddeo da campanha &#8220;Fica Gamboa&#8221;. Ap\u00f3s cada espet\u00e1culo, o p\u00fablico tem um momento de intera\u00e7\u00e3o com os artistas no PapoGamboa.<\/p>\n\n\n\n<p>Exposi\u00e7\u00e3o &#8211; &#8220;O Que H\u00e1 no Abismo&#8221; \u00e9 uma exposi\u00e7\u00e3o de&nbsp; Lila Cairo que segue em cartaz at\u00e9 mar\u00e7o e prop\u00f5e um gesto pol\u00edtico: trazer o sofrimento psicol\u00f3gico a um lugar de humanidade. Atrav\u00e9s de desenhos em nanquim, pinturas em t\u00e9cnicas mistas, esculturas e poemas, a artista convida o p\u00fablico a refletir sobre a experi\u00eancia complexa de estar no mundo enquanto ser sens\u00edvel.<\/p>\n\n\n\n<p>Campanha Fica Gamboa &#8211; Uma campanha pode ajudar na manuten\u00e7\u00e3o de um dos equipamentos culturais mais importantes de Salvador. A casa onde funciona o Teatro Gamboa, que h\u00e1 51 anos \u00e9 palco de artistas consagrados e iniciantes na cena art\u00edstica da cidade, foi posta \u00e0 venda, com a prioridade da compra para a Associa\u00e7\u00e3o Teatro Gamboa, uma organiza\u00e7\u00e3o sem fins lucrativos, composta exclusivamente por artistas, produtores culturais e t\u00e9cnicos, que gerencia o espa\u00e7o.<\/p>\n\n\n\n<p>As doa\u00e7\u00f5es podem ser feitas atrav\u00e9s do link&nbsp;<a href=\"https:\/\/www.catarse.me\/ficagamboa\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.catarse.me\/ficagamboa<\/a>. O objetivo \u00e9 arrecadar R$500 mil para a compra do im\u00f3vel e para realizar reformas. O Gamboa oferece pauta gratuita para artistas, apoio t\u00e9cnico, assessoria de imprensa, cria\u00e7\u00e3o gr\u00e1fica e o total da bilheteria revertida para as produ\u00e7\u00f5es, iniciativa poss\u00edvel porque desde 2009 recebe o apoio da Secretaria de Cultura do Estado, atrav\u00e9s do Edital de Apoio a A\u00e7\u00f5es Continuadas de Institui\u00e7\u00f5es Culturais, suporte fundamental para a perman\u00eancia das atividades do teatro a partir do investimento em sua manuten\u00e7\u00e3o, estrutura f\u00edsica e equipe t\u00e9cnica.<\/p>\n\n\n\n<p>O Teatro Gamboa \u00e9 reconhecido por ser um espa\u00e7o democr\u00e1tico que investe tanto em artistas renomados quanto em novos nomes da cena cultural do estado. Foi o primeiro palco de cantoras que, mais tarde, se tornaram nacionalmente conhecidas, como Zizi Possi e Luedji Luna.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Abrindo a programa\u00e7\u00e3o da primeira semana de mar\u00e7o, o Teatro Gamboa recebe nesta quarta (04), \u00e0s 19h, a segunda apresenta\u00e7\u00e3o<\/p>\n","protected":false},"author":1,"featured_media":1649,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[49,46],"tags":[317,319,322,321,320,318,316],"class_list":["post-1645","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-exposicoes","category-teatro","tag-agenda-cultural-salvador","tag-crianca-viada","tag-cultura-baiana","tag-exposicao-em-salvador","tag-o-avo-e-o-rio","tag-programacao-cultural-salvador","tag-teatro-gamboa"],"rttpg_featured_image_url":{"full":["https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/03\/Foto-James-Barretto-2-2-1.jpg",967,639,false],"landscape":["https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/03\/Foto-James-Barretto-2-2-1.jpg",967,639,false],"portraits":["https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/03\/Foto-James-Barretto-2-2-1.jpg",967,639,false],"thumbnail":["https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/03\/Foto-James-Barretto-2-2-1-150x150.jpg",150,150,true],"medium":["https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/03\/Foto-James-Barretto-2-2-1-300x198.jpg",300,198,true],"large":["https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/03\/Foto-James-Barretto-2-2-1.jpg",800,529,false],"1536x1536":["https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/03\/Foto-James-Barretto-2-2-1.jpg",967,639,false],"2048x2048":["https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/03\/Foto-James-Barretto-2-2-1.jpg",967,639,false],"colormag-highlighted-post":["https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/03\/Foto-James-Barretto-2-2-1-392x272.jpg",392,272,true],"colormag-featured-post-medium":["https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/03\/Foto-James-Barretto-2-2-1-390x205.jpg",390,205,true],"colormag-featured-post-small":["https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/03\/Foto-James-Barretto-2-2-1-130x90.jpg",130,90,true],"colormag-featured-image":["https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/03\/Foto-James-Barretto-2-2-1-800x445.jpg",800,445,true],"colormag-default-news":["https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/03\/Foto-James-Barretto-2-2-1-150x150.jpg",150,150,true],"colormag-featured-image-large":["https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/03\/Foto-James-Barretto-2-2-1-967x600.jpg",967,600,true],"colormag-elementor-block-extra-large-thumbnail":["https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/03\/Foto-James-Barretto-2-2-1-967x480.jpg",967,480,true],"colormag-elementor-grid-large-thumbnail":["https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/03\/Foto-James-Barretto-2-2-1-600x417.jpg",600,417,true],"colormag-elementor-grid-small-thumbnail":["https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/03\/Foto-James-Barretto-2-2-1-285x450.jpg",285,450,true],"colormag-elementor-grid-medium-large-thumbnail":["https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/03\/Foto-James-Barretto-2-2-1-575x198.jpg",575,198,true],"psacp-medium":["https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/03\/Foto-James-Barretto-2-2-1-500x500.jpg",500,500,true]},"rttpg_author":{"display_name":"boracultura@gmail.com","author_link":"https:\/\/boracultura.com.br\/index.php\/author\/boraculturagmail-com\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/boracultura.com.br\/index.php\/category\/noticias\/exposicoes\/\" rel=\"category tag\">Exposi\u00e7\u00f5es<\/a> <a href=\"https:\/\/boracultura.com.br\/index.php\/category\/noticias\/teatro\/\" rel=\"category tag\">Teatro<\/a>","rttpg_excerpt":"Abrindo a programa\u00e7\u00e3o da primeira semana de mar\u00e7o, o Teatro Gamboa recebe nesta quarta (04), \u00e0s 19h, a segunda apresenta\u00e7\u00e3o","_links":{"self":[{"href":"https:\/\/boracultura.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1645","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boracultura.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boracultura.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boracultura.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/boracultura.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=1645"}],"version-history":[{"count":1,"href":"https:\/\/boracultura.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1645\/revisions"}],"predecessor-version":[{"id":1653,"href":"https:\/\/boracultura.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1645\/revisions\/1653"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boracultura.com.br\/index.php\/wp-json\/wp\/v2\/media\/1649"}],"wp:attachment":[{"href":"https:\/\/boracultura.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=1645"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boracultura.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=1645"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boracultura.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=1645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}