{"id":3334,"date":"2026-05-07T08:43:10","date_gmt":"2026-05-07T11:43:10","guid":{"rendered":"https:\/\/boracultura.com.br\/?p=3334"},"modified":"2026-05-07T08:43:13","modified_gmt":"2026-05-07T11:43:13","slug":"celebracao-em-dose-dupla-juliana-ribeiro-ganha-segunda-data-no-teatro-sesc-casa-do-comercio","status":"publish","type":"post","link":"https:\/\/boracultura.com.br\/index.php\/2026\/05\/07\/celebracao-em-dose-dupla-juliana-ribeiro-ganha-segunda-data-no-teatro-sesc-casa-do-comercio\/","title":{"rendered":"Celebra\u00e7\u00e3o em dose dupla: Juliana Ribeiro ganha segunda data no Teatro SESC Casa do Com\u00e9rcio"},"content":{"rendered":"\n<p>A cantora, pesquisadora e atriz baiana Juliana Ribeiro ter\u00e1 n\u00e3o uma, mas duas noites de celebra\u00e7\u00e3o no Teatro SESC Casa do Com\u00e9rcio, em Salvador. O espet\u00e1culo &#8220;CELEBRA\u00c7\u00c3O: Juliana Ribeiro 25+!&#8221;, que marca os 25 anos de trajet\u00f3ria da artista, recebeu convite do Sesc para uma sess\u00e3o adicional: al\u00e9m da apresenta\u00e7\u00e3o desta sexta-feira (8), Juliana sobe ao palco novamente no dia 16 de maio, um s\u00e1bado, sempre \u00e0s 20h.<\/p>\n\n\n\n<p>A nova data surgiu da forte procura por ingressos e do reconhecimento da relev\u00e2ncia do projeto. &#8220;O convite do Sesc veio pela magnitude do show e pela celebra\u00e7\u00e3o desses 25 anos, mas tamb\u00e9m pela forte demanda de ingressos. \u00c9 uma atitude de fomento, de parceria e de quem entende o lugar do artista independente, que constr\u00f3i junto&#8221;, afirma Juliana Ribeiro.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Uma travessia por 25 anos de hist\u00f3ria<\/h2>\n\n\n\n<p>Mais do que um show, &#8220;CELEBRA\u00c7\u00c3O: Juliana Ribeiro 25+!&#8221; \u00e9 uma narrativa sens\u00edvel constru\u00edda em cima de uma trajet\u00f3ria que atravessa m\u00fasica, pesquisa, televis\u00e3o, r\u00e1dio e academia. Com o fio condutor &#8220;muita hist\u00f3ria pra cantar e muita m\u00fasica pra contar&#8221;, o espet\u00e1culo costura ancestralidade, afetos e proje\u00e7\u00f5es de futuro, conduzindo o p\u00fablico pelas mem\u00f3rias da artista \u2014 das primeiras composi\u00e7\u00f5es \u00e0s interpreta\u00e7\u00f5es que consolidaram seu nome na cena cultural baiana e nacional.<\/p><div class=\"borac-publicidade-no-post borac-entity-placement\" style=\"text-align: center;\" id=\"borac-2402298199\"><div id=\"borac-2550718706\"><a href=\"https:\/\/bileto.sympla.com.br\/event\/118627\/d\/375887\/s\/2508765\" aria-label=\"MINHA M\u00c3E E EU_teatro m\u00f3dulo (970x250px)\"><img src=\"https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/05\/MINHA-MAE-E-EU_teatro-modulo-970x250px.png\" alt=\"\"  srcset=\"https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/05\/MINHA-MAE-E-EU_teatro-modulo-970x250px.png 970w, https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/05\/MINHA-MAE-E-EU_teatro-modulo-970x250px-300x77.png 300w, https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/05\/MINHA-MAE-E-EU_teatro-modulo-970x250px-768x198.png 768w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"250\"   \/><\/a><\/div><\/div>\n\n\n\n<p>Passagens como o lan\u00e7amento do \u00e1lbum <em>Preta Brasileira<\/em> no Teatro Castro Alves, a experi\u00eancia no trio el\u00e9trico ao lado de Riach\u00e3o, mais de uma d\u00e9cada como comentarista do carnaval na televis\u00e3o e a participa\u00e7\u00e3o no programa <em>Clave de Sol<\/em>, na R\u00e1dio Educadora, ganham espa\u00e7o na encena\u00e7\u00e3o. A maternidade e os estudos acad\u00eamicos tamb\u00e9m comp\u00f5em esse mosaico autobiogr\u00e1fico.<\/p>\n\n\n\n<p>Em ambas as noites, Juliana conta com a participa\u00e7\u00e3o da atriz premiada B\u00e1rbara Borga, que cria interse\u00e7\u00f5es teatrais para dar voz a diferentes dimens\u00f5es da trajet\u00f3ria da artista \u2014 pesquisadora, m\u00e3e e apresentadora.<br><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Repert\u00f3rio e equipe<\/h2>\n\n\n\n<p>O setlist re\u00fane can\u00e7\u00f5es dos tr\u00eas \u00e1lbuns da artista \u2014 <em>Juliana Ribeiro<\/em> (2009), <em>Amarelo<\/em> (2011) e <em>Preta Brasileira<\/em> (2021) \u2014, com faixas como &#8220;Beira de Mar\u00e9&#8221;, &#8220;Eu Vim das \u00c1guas&#8221;, &#8220;Ella&#8221;, &#8220;Semba de Angola&#8221;, &#8220;Drag\u00e3o de Gaud\u00ed&#8221; e &#8220;Preta Brasileira&#8221;, al\u00e9m da releitura de &#8220;Z\u00e9 do Caro\u00e7o&#8221;. Cada m\u00fasica chega acompanhada de hist\u00f3rias que revelam os bastidores da cria\u00e7\u00e3o.<\/p>\n\n\n\n<p>Com dire\u00e7\u00e3o art\u00edstica de Andrez\u00e3o Sim\u00f5es, o espet\u00e1culo recria cen\u00e1rios simb\u00f3licos ligados \u00e0 vida de Juliana \u2014 sua casa, seus territ\u00f3rios de inspira\u00e7\u00e3o. No dia 16, a banda ser\u00e1 formada por Ruan de Souza (viola e dire\u00e7\u00e3o musical), Estevam Dantas (piano e sanfona), Talita Felicio (baixo ac\u00fastico), Indira Dourado (clarineta), Thiago Ramalho (bateria) e Antenor Cardoso (percuss\u00f5es). A produ\u00e7\u00e3o \u00e9 assinada por C\u00ednthia Santiago, com assist\u00eancia de Didica Couto. Cenografia de Zuarte Junior, luz de Fernanda Mascarenhas e figurino de Renato da Katuka Africanidades.<\/p>\n\n\n\n<p>O espet\u00e1culo tem patroc\u00ednio da Bahiag\u00e1s e reafirma o percurso de Juliana Ribeiro como artista m\u00faltipla que une m\u00fasica, pesquisa e identidade cultural em obra de f\u00f4lego \u2014 uma mulher negra e independente que transforma trajet\u00f3ria em legado.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p><strong>SERVI\u00c7O<\/strong><br><strong>Show:<\/strong> &#8220;Celebra\u00e7\u00e3o: Juliana Ribeiro 25+!&#8221;<br><strong>Artista:<\/strong> Juliana Ribeiro<br><strong>Datas:<\/strong> 8 de maio de 2026 (sexta-feira) e 16 de maio de 2026 (s\u00e1bado), \u00e0s 20h<br><strong>Local:<\/strong> Teatro SESC Casa do Com\u00e9rcio \u2014 Salvador (BA)<br><strong>Ingressos:<\/strong> R$ 20 (inteira) \/ R$ 10 (meia-entrada)<br><strong>Classifica\u00e7\u00e3o:<\/strong> Livre<br><strong>Vendas:<\/strong> https:\/\/www.sympla.com.br<\/p>\n","protected":false},"excerpt":{"rendered":"<p> A cantora baiana Juliana Ribeiro ganha segunda data no Teatro SESC Casa do Com\u00e9rcio com o show &#8220;CELEBRA\u00c7\u00c3O: Juliana Ribeiro 25+!&#8221;, nos dias 8 e 16 de maio, \u00e0s 20h. Ingressos a partir de R$ 10.<\/p>\n","protected":false},"author":1,"featured_media":3335,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[45],"tags":[1494,342,760,20,804],"class_list":["post-3334","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-musica","tag-juliana-ribeiro","tag-musica-baiana","tag-musica-brasileira","tag-sesc-casa-do-comercio","tag-show-salvador"],"rttpg_featured_image_url":{"full":["https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/05\/17781541068984034406978731946105-scaled.jpg",2560,1698,false],"landscape":["https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/05\/17781541068984034406978731946105-scaled.jpg",2560,1698,false],"portraits":["https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/05\/17781541068984034406978731946105-scaled.jpg",2560,1698,false],"thumbnail":["https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/05\/17781541068984034406978731946105-150x150.jpg",150,150,true],"medium":["https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/05\/17781541068984034406978731946105-300x199.jpg",300,199,true],"large":["https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/05\/17781541068984034406978731946105-1024x679.jpg",800,530,true],"1536x1536":["https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/05\/17781541068984034406978731946105-1536x1019.jpg",1536,1019,true],"2048x2048":["https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/05\/17781541068984034406978731946105-2048x1358.jpg",2048,1358,true],"colormag-highlighted-post":["https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/05\/17781541068984034406978731946105-392x272.jpg",392,272,true],"colormag-featured-post-medium":["https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/05\/17781541068984034406978731946105-390x205.jpg",390,205,true],"colormag-featured-post-small":["https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/05\/17781541068984034406978731946105-130x90.jpg",130,90,true],"colormag-featured-image":["https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/05\/17781541068984034406978731946105-800x445.jpg",800,445,true],"colormag-default-news":["https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/05\/17781541068984034406978731946105-150x150.jpg",150,150,true],"colormag-featured-image-large":["https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/05\/17781541068984034406978731946105-1400x600.jpg",1400,600,true],"colormag-elementor-block-extra-large-thumbnail":["https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/05\/17781541068984034406978731946105-1155x480.jpg",1155,480,true],"colormag-elementor-grid-large-thumbnail":["https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/05\/17781541068984034406978731946105-600x417.jpg",600,417,true],"colormag-elementor-grid-small-thumbnail":["https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/05\/17781541068984034406978731946105-285x450.jpg",285,450,true],"colormag-elementor-grid-medium-large-thumbnail":["https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/05\/17781541068984034406978731946105-575x198.jpg",575,198,true],"psacp-medium":["https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/05\/17781541068984034406978731946105-500x500.jpg",500,500,true]},"rttpg_author":{"display_name":"boracultura@gmail.com","author_link":"https:\/\/boracultura.com.br\/index.php\/author\/boraculturagmail-com\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/boracultura.com.br\/index.php\/category\/noticias\/musica\/\" rel=\"category tag\">M\u00fasica<\/a>","rttpg_excerpt":"A cantora baiana Juliana Ribeiro ganha segunda data no Teatro SESC Casa do Com\u00e9rcio com o show \"CELEBRA\u00c7\u00c3O: Juliana Ribeiro 25+!\", nos dias 8 e 16 de maio, \u00e0s 20h. Ingressos a partir de R$ 10.","_links":{"self":[{"href":"https:\/\/boracultura.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boracultura.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boracultura.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boracultura.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/boracultura.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=3334"}],"version-history":[{"count":1,"href":"https:\/\/boracultura.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3334\/revisions"}],"predecessor-version":[{"id":3337,"href":"https:\/\/boracultura.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3334\/revisions\/3337"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boracultura.com.br\/index.php\/wp-json\/wp\/v2\/media\/3335"}],"wp:attachment":[{"href":"https:\/\/boracultura.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=3334"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boracultura.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=3334"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boracultura.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=3334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}