{"id":3175,"date":"2026-05-01T19:12:55","date_gmt":"2026-05-01T22:12:55","guid":{"rendered":"https:\/\/boracultura.com.br\/?post_type=tribe_events&#038;p=3175"},"modified":"2026-05-01T19:13:22","modified_gmt":"2026-05-01T22:13:22","slug":"roda-de-samba-grupo-botequim","status":"publish","type":"tribe_events","link":"https:\/\/boracultura.com.br\/index.php\/agenda\/roda-de-samba-grupo-botequim\/","title":{"rendered":"Roda de Samba &#8211; Grupo Botequim"},"content":{"rendered":"<p>Mantendo viva a tradi\u00e7\u00e3o das rodas de samba em Salvador, o Grupo Botequim realiza, no dia 8 de maio, mais uma edi\u00e7\u00e3o do seu encontro mensal no P\u00e1tio da Igreja do Santo Ant\u00f4nio Al\u00e9m do Carmo. A partir das 21h, o grupo recebe a cantora Maira Lins e o coletivo Fragmentos do Samba, em uma noite que conecta diferentes linguagens e gera\u00e7\u00f5es do g\u00eanero, reafirmando o espa\u00e7o como um dos principais pontos de resist\u00eancia e celebra\u00e7\u00e3o do samba na cidade.<\/p>\r\n\r\n<p><strong>SERVI\u00c7O<\/strong> <strong>Roda de Samba de Maio &#8211; Grupo Botequim<\/strong> <strong>Convidados: <\/strong>Maira Lins e Fragmentos do Samba <strong>Local:<\/strong> P\u00e1tio da Igreja do Santo Ant\u00f4nio Al\u00e9m do Carmo <strong>Data:<\/strong> 08\/05 (sexta-feira) <strong>Hor\u00e1rio:<\/strong> 21h | Abertura da casa \u00e0s 20h <strong>Ingressos:<\/strong> <a href=\"https:\/\/www.sympla.com.br\/evento\/roda-de-samba-do-grupo-botequim-edicao-de-maio\/3390412\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.sympla.com.br\/evento\/roda-de-samba-do-grupo-botequim-edicao-de-maio\/3390412<\/a><\/p>\r\n\r\n\r\n\r\n<p><strong>Maira Lins (Foto: Divulga\u00e7\u00e3o) | Fragmentos do Samba (Foto: Divulga\u00e7\u00e3o) | Grupo Botequim (Foto: Daniel Pita)<\/strong><\/p><div class=\"borac-publicidade-no-post borac-entity-placement\" style=\"text-align: center;\" id=\"borac-2063316575\"><div id=\"borac-88143002\"><a href=\"https:\/\/bileto.sympla.com.br\/event\/118627\/d\/375887\/s\/2508765\" aria-label=\"MINHA M\u00c3E E EU_teatro m\u00f3dulo (970x250px)\"><img src=\"https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/05\/MINHA-MAE-E-EU_teatro-modulo-970x250px.png\" alt=\"\"  srcset=\"https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/05\/MINHA-MAE-E-EU_teatro-modulo-970x250px.png 970w, https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/05\/MINHA-MAE-E-EU_teatro-modulo-970x250px-300x77.png 300w, https:\/\/boracultura.com.br\/wp-content\/uploads\/2026\/05\/MINHA-MAE-E-EU_teatro-modulo-970x250px-768x198.png 768w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"250\"   \/><\/a><\/div><\/div>\r\n","protected":false},"excerpt":{"rendered":"<p>O Grupo Botequim realiza mais uma edi\u00e7\u00e3o de sua tradicional roda de samba no dia 8 de maio, \u00e0s 21h, no P\u00e1tio da Igreja do Santo Ant\u00f4nio Al\u00e9m do Carmo, em Salvador. A noite conta com participa\u00e7\u00f5es da cantora Maira Lins e do coletivo Fragmentos do Samba, que traz uma abordagem contempor\u00e2nea ao g\u00eanero.<\/p>\n","protected":false},"author":1,"featured_media":3173,"template":"","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[317,1862,230,1861,342,1863,1864,718,721,1859],"tribe_events_cat":[97],"class_list":["post-3175","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tag-agenda-cultural-salvador","tag-fragmentos-do-samba","tag-grupo-botequim","tag-maira-lins","tag-musica-baiana","tag-roda-de-samba-salvador","tag-samba-contemporaneo","tag-samba-em-salvador","tag-santo-antonio-alem-do-carmo","tag-shows-em-salvador","tribe_events_cat-musica","cat_musica"],"_links":{"self":[{"href":"https:\/\/boracultura.com.br\/index.php\/wp-json\/wp\/v2\/tribe_events\/3175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boracultura.com.br\/index.php\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/boracultura.com.br\/index.php\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/boracultura.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":2,"href":"https:\/\/boracultura.com.br\/index.php\/wp-json\/wp\/v2\/tribe_events\/3175\/revisions"}],"predecessor-version":[{"id":3177,"href":"https:\/\/boracultura.com.br\/index.php\/wp-json\/wp\/v2\/tribe_events\/3175\/revisions\/3177"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boracultura.com.br\/index.php\/wp-json\/wp\/v2\/media\/3173"}],"wp:attachment":[{"href":"https:\/\/boracultura.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=3175"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boracultura.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=3175"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/boracultura.com.br\/index.php\/wp-json\/wp\/v2\/tribe_events_cat?post=3175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}